{"id":2238,"date":"2024-08-06T19:54:26","date_gmt":"2024-08-06T17:54:26","guid":{"rendered":"https:\/\/epicpowerlifts.com\/success-stories\/ascensores-alimentacion-solar\/"},"modified":"2025-08-29T11:22:10","modified_gmt":"2025-08-29T09:22:10","slug":"ascensores-alimentacion-solar","status":"publish","type":"caso-de-exito","link":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/","title":{"rendered":"Ascensores monof\u00e1sicos con alimentaci\u00f3n solar en edificio residencial. Un caso de \u00e9xito."},"content":{"rendered":"\n<div class=\"wp-block-group has-global-padding is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c3f8e3ad wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns are-vertically-aligned-bottom is-layout-flex wp-container-core-columns-is-layout-203f3c05 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-safe-svg-svg-icon safe-svg-cover\" style=\"text-align: right;\">\n\t\t\t\t<div class=\"safe-svg-inside safe-svg-inline\" style=\"width: 42px; height: 26px; background-color: var(--wp--preset--color--); color: var(--wp--preset--color--); padding-top: ; padding-right: ; padding-bottom: ; padding-left: ; margin-top: ; margin-right: ; margin-bottom: ; margin-left: ;\"><?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"42\" height=\"26\" viewBox=\"0 0 42 26\" fill=\"none\"><g id=\"Brand\/Flecha\"><path id=\"Brand\/Flecha_2\" d=\"M1.99683 5.99872V3.99693H0V5.99872H1.99683ZM1.99683 2.00013V0H0V2.00013H1.99683ZM6.00048 10.0006V8.00051H3.99533V10.0006H6.00048ZM6.00048 5.99872V3.99693H3.99533V5.99872H6.00048ZM6.00048 2.00013V0H3.99533V2.00013H6.00048ZM9.99913 13.9976V11.9991H7.99897V13.9976H9.99913ZM9.99913 10.0006V8.00051H7.99897V10.0006H9.99913ZM9.99913 5.99872V3.99693H7.99897V5.99872H9.99913ZM9.99913 2.00013V0H7.99897V2.00013H9.99913ZM13.9994 18.0028V15.9994H12.0026V18.0028H13.9994ZM13.9994 13.9976V11.9991H12.0026V13.9976H13.9994ZM13.9994 10.0006V8.00051H12.0026V10.0006H13.9994ZM13.9994 5.99872V3.99693H12.0026V5.99872H13.9994ZM17.9998 21.9997V19.998H16.0046V22.0014L17.9998 21.9997ZM17.9998 18.0028V15.9994H16.0046V18.0028H17.9998ZM17.9998 13.9976V11.9991H16.0046V13.9976H17.9998ZM17.9998 10.0006V8.00051H16.0046V10.0006H17.9998ZM22.0001 26V23.9965H19.9966V26H22.0001ZM22.0001 21.9997V19.998H19.9966V22.0014L22.0001 21.9997ZM22.0001 18.0028V15.9994H19.9966V18.0028H22.0001ZM22.0017 13.9976V11.9991H19.9966V13.9976H22.0017ZM26.0037 21.9997V19.998H23.9986V22.0014L26.0037 21.9997ZM26.0037 18.0028V15.9994H23.9986V18.0028H26.0037ZM26.0037 13.9976V11.9991H23.9986V13.9976H26.0037ZM26.0037 10.0006V8.00051H23.9986V10.0006H26.0037ZM30.0007 18.0028V15.9994H28.0022V18.0028H30.0007ZM30.0007 13.9976V11.9991H28.0022V13.9976H30.0007ZM30.0007 10.0006V8.00051H28.0022V10.0006H30.0007ZM30.0007 5.99872V3.99693H28.0022V5.99872H30.0007ZM33.9994 13.9976V11.9991H31.9975V13.9976H33.9994ZM33.9994 10.0006V8.00051H31.9975V10.0006H33.9994ZM33.9994 5.99872V3.99693H31.9975V5.99872H33.9994ZM33.9994 2.00013V0H31.9975V2.00013H33.9994ZM37.9997 10.0006V8.00051H35.9995V10.0006H37.9997ZM37.9997 5.99872V3.99693H35.9995V5.99872H37.9997ZM37.9997 2.00013V0H35.9995V2.00013H37.9997ZM42 5.99872V3.99693H40.0015V5.99872H42ZM42 2.00013V0H40.0015V2.00013H42Z\" fill=\"#0064E2\"><\/path><\/g><\/svg> <\/div>\n\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-heading-3-font-size\">A continuaci\u00f3n presentamos un caso de una comunidad de vecinos con tres ascensores que decidieron equipar con soluciones de gesti\u00f3n inteligente de energ\u00eda y alimentaci\u00f3n solar, para obtener beneficios tanto econ\u00f3micos como de eficiencia energ\u00e9tica.<\/h2>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-top-color:var(--wp--preset--color--neutral-30);border-top-width:1px;border-bottom-color:var(--wp--preset--color--neutral-30);border-bottom-width:1px;margin-top:var(--wp--preset--spacing--60);padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<p class=\"has-primary-color has-text-color has-link-color has-small-font-size wp-elements-f884c4932222d2f3e39a09e932b2ae15 wp-block-paragraph\" style=\"text-transform:uppercase\">Reto<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-22d38bb3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<h2 class=\"wp-block-heading\">Ascensores con 30 a\u00f1os de antig\u00fcedad<\/h2>\n\n\n\n<p class=\"scroll--reveal-text\" style=\"--n: 250\"><span> La comunidad de propietarios deseaba modernizar sus ascensores, que ya contaban con casi 30 a\u00f1os de antig\u00fcedad. Para ello, a trav\u00e9s del administrador , contactaron con varias empresas de mantenimiento y modernizaci\u00f3n de ascensores en busca de soluciones. <\/span><\/p>\n\n\n\n<p class=\"has-text-medium-color has-text-color has-link-color has-small-font-size wp-elements-d7bd127cd5cc9444ca673f1f8d63f884 wp-block-paragraph\">La comunidad estaba especialmente preocupada por el consumo energ\u00e9tico del edificio, que ya era elevado debido a diferentes factores, incluidos los tres ascensores existentes. El problema no era solo el alto consumo energ\u00e9tico, sino tambi\u00e9n la alta potencia contratada, lo que incrementaba notablemente los costos de la comunidad. <\/p>\n\n\n\n<p class=\"has-text-medium-color has-text-color has-link-color has-small-font-size wp-elements-8b2bb0d82d1bf8389c175753f8f41525 wp-block-paragraph\">Adem\u00e1s tras algunos cortes de luz en el edificio hab\u00edan tenido alg\u00fan caso de vecinos atrapados en el ascensor.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"803\" src=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/new-elevators-single-phase-solar-powered-P2S-epic-power-1024x803.jpg\" alt=\"\" class=\"wp-image-2224\" srcset=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/new-elevators-single-phase-solar-powered-P2S-epic-power-1024x803.jpg 1024w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/new-elevators-single-phase-solar-powered-P2S-epic-power-300x235.jpg 300w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/new-elevators-single-phase-solar-powered-P2S-epic-power-768x602.jpg 768w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/new-elevators-single-phase-solar-powered-P2S-epic-power.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n<div class=\"wp-block-group alignfull has-neutral-10-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--80)\">\n<p class=\"has-primary-color has-text-color has-link-color has-small-font-size wp-elements-2abe4139a5f17deff7cc2b476cd3c6b8 wp-block-paragraph\" style=\"text-transform:uppercase\">Soluci\u00f3n<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-203f3c05 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">P2S solar (Alimentaci\u00f3n monof\u00e1sica solar). La soluci\u00f3n aportada<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top hidden-mobile hidden-tablet is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:8%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Una de las empresas de ascensores contactada, atenta a las necesidades energ\u00e9ticas de sus clientes, propuso a la comunidad modernizar los ascensores utilizando la <a href=\"https:\/\/epicpowerlifts.com\/es\/productos\/p2s-sistema-de-alimentacion-monofasica\/\" data-type=\"page\" data-id=\"1875\"><strong>soluci\u00f3n P2S<\/strong> (Sistema de alimentaci\u00f3n monof\u00e1sica para ascensores)<\/a> de Epic Power.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya la hab\u00edan utilizado antes en otras instalaciones, con muy buenos resultados. Esta soluci\u00f3n permite instalar ascensores monof\u00e1sicos con una potencia m\u00e1xima de solo 500 W, ofreciendo las mismas prestaciones que un ascensor trif\u00e1sico con consumos de hasta 6 kW por ascensor. Tambi\u00e9n permite la conexi\u00f3n con paneles solares, eliminando por completo el consumo de los ascensores durante las horas de luz solar.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">En la gr\u00e1fica inferior se puede ver la utilizaci\u00f3n de uno de los ascensores consumiendo energ\u00eda solar (color naranja) y consumo de la red el\u00e9ctrica (azul), durante 5 d\u00edas. Los picos naranjas corresponden con las horas de sol. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"464\" src=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/consumption-graph-solar-powererd-elevators-P2S-epic-power-1024x464.jpg\" alt=\"\" class=\"wp-image-2226\" srcset=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/consumption-graph-solar-powererd-elevators-P2S-epic-power-1024x464.jpg 1024w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/consumption-graph-solar-powererd-elevators-P2S-epic-power-300x136.jpg 300w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/consumption-graph-solar-powererd-elevators-P2S-epic-power-768x348.jpg 768w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/consumption-graph-solar-powererd-elevators-P2S-epic-power-1536x696.jpg 1536w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/consumption-graph-solar-powererd-elevators-P2S-epic-power.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--30)\">\n<p class=\"has-primary-color has-text-color has-link-color has-small-font-size wp-elements-ccdce3689cd4a81f50ef6fda70ddacde wp-block-paragraph\" style=\"text-transform:uppercase\">Beneficio conseguido<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-22d38bb3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<h2 class=\"wp-block-heading\">Soluciones monof\u00e1sicas con integraci\u00f3n solar para ascensores<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list is-style-arrow-separator-list\">\n<li>Reducci\u00f3n del 53% en el consumo de energ\u00eda<\/li>\n\n\n\n<li>Reducci\u00f3n de 15kW en la potencia contratada<\/li>\n\n\n\n<li>1.690\u20ac de ahorro estimado anual<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la implementaci\u00f3n de la soluci\u00f3n monof\u00e1sica P2S de los tres ascensores junto a la integraci\u00f3n solar, la comunidad ha conseguido reducir el consumo energ\u00e9tico en un 53% en comparaci\u00f3n con la situaci\u00f3n inicial. Adem\u00e1s, se logr\u00f3 una reducci\u00f3n de m\u00e1s de 15 kW en la potencia contratada, lo que representa un ahorro anual de aproximadamente 1.690 \u20ac*, considerando tanto la disminuci\u00f3n de la potencia contratada como la reducci\u00f3n del consumo energ\u00e9tico. <\/p>\n\n\n\n<p class=\"has-neutral-80-color has-text-color has-link-color has-small-font-size wp-elements-4198c7c98c48d570947572e85875b817 wp-block-paragraph\">*Dato aproximado, teniendo en cuenta el precio por kWh a Diciembre de 2024.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-203f3c05 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"1024\" src=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/electrical-cabinet-components-single-phase-solar-powered-elevator-P2S-epic-power-617x1024.jpg\" alt=\"\" class=\"wp-image-2228\" srcset=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/electrical-cabinet-components-single-phase-solar-powered-elevator-P2S-epic-power-617x1024.jpg 617w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/electrical-cabinet-components-single-phase-solar-powered-elevator-P2S-epic-power-181x300.jpg 181w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/electrical-cabinet-components-single-phase-solar-powered-elevator-P2S-epic-power.jpg 723w\" sizes=\"auto, (max-width: 617px) 100vw, 617px\" \/><figcaption class=\"wp-element-caption\">Detalle de uno de los sistemas P2S instalados en el edificio residencial<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"491\" src=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/components-connections-diagram-P2S-epic-power-1024x491.png\" alt=\"\" class=\"wp-image-2230\" srcset=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/components-connections-diagram-P2S-epic-power-1024x491.png 1024w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/components-connections-diagram-P2S-epic-power-300x144.png 300w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/components-connections-diagram-P2S-epic-power-768x368.png 768w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/components-connections-diagram-P2S-epic-power.png 1183w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Esquem\u00e1tico de conexiones del sistema de alimentaci\u00f3n monof\u00e1sica P2S<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-203f3c05 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/usage-graph-single-phase-elevator-solar-P2S-epic-power-1024x683.jpg\" alt=\"\" class=\"wp-image-2232\" srcset=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/usage-graph-single-phase-elevator-solar-P2S-epic-power-1024x683.jpg 1024w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/usage-graph-single-phase-elevator-solar-P2S-epic-power-300x200.jpg 300w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/usage-graph-single-phase-elevator-solar-P2S-epic-power-768x512.jpg 768w, https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/usage-graph-single-phase-elevator-solar-P2S-epic-power.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Detalle de pantalla de monitorizaci\u00f3n de picos de consumo de bater\u00eda<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">El sistema tiene la posibilidad de ser monitorizado para obtener informaci\u00f3n detallada de viajes, consumos, carga de bater\u00edas, etc. Toda esta informaci\u00f3n es muy valiosa para detectar posibles anomal\u00edas en el funcionamiento del ascensor, as\u00ed como para hacer un mantenimiento predictivo. <\/p>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">\u00bfQuieres saber m\u00e1s sobre las soluciones de gesti\u00f3n inteligente de la energ\u00eda para ascensores?<br\/><strong><a href=\"\/epic-lift?page_id=1886\" data-type=\"page\" data-id=\"1886\">\u00a1Contacta con nosotros!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soluci\u00f3n: P2S (opci\u00f3n solar)<br \/>\nZaragoza &#8211; Edificio de viviendas<br \/>\n10 paradas<\/p>\n","protected":false},"featured_media":2235,"menu_order":0,"template":"","dlm_download_category":[47],"class_list":["post-2238","caso-de-exito","type-caso-de-exito","status-publish","has-post-thumbnail","hentry","dlm_download_category-p2s-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ascensores con alimentaci\u00f3n solar en edificio residencial.<\/title>\n<meta name=\"description\" content=\"Caso de \u00e9xito de modernizaci\u00f3n de ascensores monof\u00e1sicos con alimentaci\u00f3n solar y tecnolog\u00eda P2S de epic power.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ascensores con alimentaci\u00f3n solar en edificio residencial.\" \/>\n<meta property=\"og:description\" content=\"Caso de \u00e9xito de modernizaci\u00f3n de ascensores monof\u00e1sicos con alimentaci\u00f3n solar y tecnolog\u00eda P2S de epic power.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/\" \/>\n<meta property=\"og:site_name\" content=\"Epic Power Lifts\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:22:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/\",\"url\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/\",\"name\":\"Ascensores con alimentaci\u00f3n solar en edificio residencial.\",\"isPartOf\":{\"@id\":\"https:\/\/epicpowerlifts.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg\",\"datePublished\":\"2024-08-06T17:54:26+00:00\",\"dateModified\":\"2025-08-29T09:22:10+00:00\",\"description\":\"Caso de \u00e9xito de modernizaci\u00f3n de ascensores monof\u00e1sicos con alimentaci\u00f3n solar y tecnolog\u00eda P2S de epic power.\",\"breadcrumb\":{\"@id\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#primaryimage\",\"url\":\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg\",\"contentUrl\":\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg\",\"width\":1200,\"height\":748,\"caption\":\"Paneles solares en una vivienda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Epic Power LIfts\",\"item\":\"https:\/\/epicpowerlifts.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casos de \u00e9xito\",\"item\":\"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ascensores monof\u00e1sicos con alimentaci\u00f3n solar en edificio residencial. Un caso de \u00e9xito.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/epicpowerlifts.com\/es\/#website\",\"url\":\"https:\/\/epicpowerlifts.com\/es\/\",\"name\":\"Epic Power Lifts\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/epicpowerlifts.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/epicpowerlifts.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/epicpowerlifts.com\/es\/#organization\",\"name\":\"Epic Power Lifts\",\"url\":\"https:\/\/epicpowerlifts.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/epicpowerlifts.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/12\/logo-epic-lifts-division.svg\",\"contentUrl\":\"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/12\/logo-epic-lifts-division.svg\",\"width\":338,\"height\":67,\"caption\":\"Epic Power Lifts\"},\"image\":{\"@id\":\"https:\/\/epicpowerlifts.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ascensores con alimentaci\u00f3n solar en edificio residencial.","description":"Caso de \u00e9xito de modernizaci\u00f3n de ascensores monof\u00e1sicos con alimentaci\u00f3n solar y tecnolog\u00eda P2S de epic power.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/","og_locale":"es_ES","og_type":"article","og_title":"Ascensores con alimentaci\u00f3n solar en edificio residencial.","og_description":"Caso de \u00e9xito de modernizaci\u00f3n de ascensores monof\u00e1sicos con alimentaci\u00f3n solar y tecnolog\u00eda P2S de epic power.","og_url":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/","og_site_name":"Epic Power Lifts","article_modified_time":"2025-08-29T09:22:10+00:00","og_image":[{"width":1200,"height":748,"url":"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/","url":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/","name":"Ascensores con alimentaci\u00f3n solar en edificio residencial.","isPartOf":{"@id":"https:\/\/epicpowerlifts.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#primaryimage"},"image":{"@id":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg","datePublished":"2024-08-06T17:54:26+00:00","dateModified":"2025-08-29T09:22:10+00:00","description":"Caso de \u00e9xito de modernizaci\u00f3n de ascensores monof\u00e1sicos con alimentaci\u00f3n solar y tecnolog\u00eda P2S de epic power.","breadcrumb":{"@id":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#primaryimage","url":"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg","contentUrl":"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/08\/pv-panels-powering-single-phase-elevator-P2S-epic-power.jpg","width":1200,"height":748,"caption":"Paneles solares en una vivienda"},{"@type":"BreadcrumbList","@id":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/ascensores-alimentacion-solar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Epic Power LIfts","item":"https:\/\/epicpowerlifts.com\/es\/"},{"@type":"ListItem","position":2,"name":"Casos de \u00e9xito","item":"https:\/\/epicpowerlifts.com\/es\/casos-de-exito\/"},{"@type":"ListItem","position":3,"name":"Ascensores monof\u00e1sicos con alimentaci\u00f3n solar en edificio residencial. Un caso de \u00e9xito."}]},{"@type":"WebSite","@id":"https:\/\/epicpowerlifts.com\/es\/#website","url":"https:\/\/epicpowerlifts.com\/es\/","name":"Epic Power Lifts","description":"","publisher":{"@id":"https:\/\/epicpowerlifts.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/epicpowerlifts.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/epicpowerlifts.com\/es\/#organization","name":"Epic Power Lifts","url":"https:\/\/epicpowerlifts.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/epicpowerlifts.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/12\/logo-epic-lifts-division.svg","contentUrl":"https:\/\/epicpowerlifts.com\/wp-content\/uploads\/2024\/12\/logo-epic-lifts-division.svg","width":338,"height":67,"caption":"Epic Power Lifts"},"image":{"@id":"https:\/\/epicpowerlifts.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/epicpowerlifts.com\/es\/wp-json\/wp\/v2\/caso-de-exito\/2238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/epicpowerlifts.com\/es\/wp-json\/wp\/v2\/caso-de-exito"}],"about":[{"href":"https:\/\/epicpowerlifts.com\/es\/wp-json\/wp\/v2\/types\/caso-de-exito"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/epicpowerlifts.com\/es\/wp-json\/wp\/v2\/media\/2235"}],"wp:attachment":[{"href":"https:\/\/epicpowerlifts.com\/es\/wp-json\/wp\/v2\/media?parent=2238"}],"wp:term":[{"taxonomy":"dlm_download_category","embeddable":true,"href":"https:\/\/epicpowerlifts.com\/es\/wp-json\/wp\/v2\/dlm_download_category?post=2238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}